{"id":1400,"date":"2021-06-13T14:12:27","date_gmt":"2021-06-13T18:12:27","guid":{"rendered":"http:\/\/fass.ca\/dev\/?page_id=1400"},"modified":"2022-07-23T18:26:05","modified_gmt":"2022-07-23T22:26:05","slug":"lequipe-du-fass-2021","status":"publish","type":"page","link":"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/","title":{"rendered":"L&#8217;\u00e9quipe du FASS 2021"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3>COMIT\u00c9 EX\u00c9CUTIF ET CONSEIL D&#8217;ADMINISTRATION<\/h3>\n<p><strong>Fondateur et pr\u00e9sident \u00e9m\u00e9rite<\/strong>\u00a0|\u00a0Lou Gordon &#8211; Ing.P.<br \/>\n<strong>Pr\u00e9sident<\/strong>\u00a0|\u00a0Jean-Louis Hamel*<br \/>\n<strong>Vice-pr\u00e9sidents<\/strong> |\u00a0Richard J. Renaud, C.M.* &#8211; TNG Corporation et Jonathan Wener, C.M.* &#8211; Canderel Management inc.<br \/>\n<strong>Tr\u00e9sorier<\/strong> |\u00a0Pierre Urquart &#8211; Chambre de commerce de la Vall\u00e9e de Saint-Sauveur<\/p>\n<h3>MEMBRES DU CONSEIL D&#8217;ADMINISTRATION<\/h3>\n<p>Caroline Archambault &#8211; Galerie ROD<br \/>\nNick Bakish &#8211; Bakish Wealth<br \/>\nKari Cullen<br \/>\nKrista Kerr* &#8211; Kerr Financial inc.<br \/>\nCarole Laure<br \/>\nNormand Leroux &#8211; Ville de Saint-Sauveur<br \/>\nReford MacDougall<br \/>\nHugues N\u00e9ron &#8211; Le Saint-Sau Pub Gourmand<br \/>\nLeslie Silver<br \/>\nNan Wiseman &#8211; Gistex<br \/>\nJack Wiseman* &#8211; Les Galeries des Monts<\/p>\n<p>*Membre du comit\u00e9 ex\u00e9cutif[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;734&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_custom_heading text=&#8221;Guillaume C\u00f4t\u00e9 et Etienne Lavigne avec le Prix Opus 2020. Photo : Thomas Payette.&#8221; font_container=&#8221;tag:p|font_size:14px|text_align:left|color:%23636363&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3>\u00c9QUIPE PERMANENTE<\/h3>\n<p><strong>Directeur artistique<\/strong> | Guillaume C\u00f4t\u00e9 C.Q.<br \/>\n<strong>Directeur g\u00e9n\u00e9ral<\/strong>\u00a0| Etienne Lavigne<br \/>\n<strong>Directrice des op\u00e9rations<\/strong>\u00a0|\u00a0Marie-Claude Morin<br \/>\n<strong>Adjointe administrative<\/strong>\u00a0|\u00a0Louise Lecompte<\/p>\n<h3>\u00c9QUIPE 2021<\/h3>\n<p><strong>Directeur technique<\/strong> | Alain Carpentier<br \/>\n<strong>\u00c9clairagiste<\/strong> | St\u00e9phane M\u00e9nigot<br \/>\n<strong>Sonorisateur<\/strong> | Guy Goudreau<br \/>\n<strong>R\u00e9gisseurs<\/strong> | Milan St-Pierre | Jean-Hugues Rochette<br \/>\n<strong>Chefs \u00e9lectriques<\/strong> | Rachel Reard | Judith R\u00e9millard<br \/>\n<strong>Assistant.e.s production<\/strong> | Martin Poitras | Olivia Fontaine-Labrecque<br \/>\n<strong>Agent aux communications et billetterie<\/strong> | \u00c9tienne Robidoux<br \/>\n<strong>Consultant.e.s<\/strong> |\u00a0Claire Massicotte | Jacques Delisle<br \/>\n<strong>Responsable des relations de presse<\/strong>\u00a0|\u00a0IXION Communications<br \/>\n<strong>R\u00e9daction<\/strong>\u00a0|\u00a0Anne Viau<br \/>\n<strong>Traduction<\/strong>\u00a0|\u00a0Anne Viau |\u00a0Mich\u00e8le Deslandes<br \/>\n<strong>Conception graphique et site Web<\/strong>\u00a0|\u00a0Gris Gris Design[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;732&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_custom_heading text=&#8221;L&#8217;\u00e9quipe du FASS. Photo : Alexandra Laperri\u00e8re.&#8221; font_container=&#8221;tag:p|font_size:14px|text_align:left|color:%23636363&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][\/vc_row_inner][vc_custom_heading text=&#8221;MERCI AUX B\u00c9N\u00c9VOLES !&#8221; font_container=&#8221;tag:h4|font_size:30|text_align:left|color:%23999999|line_height:1.6&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; el_class=&#8221;citation&#8221;][vc_column_text]\n<h3>Chefs d\u2019\u00e9quipes 2019 :<\/h3>\n<p>Estelle Denise Boyer, Daniel Chenevert, Brigitte Lapointe, Christine Latour, Jocelyne Laurencelle, Charline Lavoie, Hubert Leduc et Lois Russel.<\/p>\n<h3>B\u00e9n\u00e9voles 2019 :<\/h3>\n<p>Karen Adelson, Shirley Adelson, Gilles Anctil, Julie Anctil, Margo Arpin, Jocelyne Aubertin, Pascale Auger, Francine Aylestock, France Beaulieu, Claire B\u00e9liveau, Dany Bellande, Paule Belleau, Diane Bid\u00e9gar\u00e9, Ren\u00e9e Blouin, Madeleine Bock, Paul Boileau, Diane Boisclair, Line Boucher, Sue Brotherwood, Gaston Brunet, Brenda Burridge, Louise Charbonneau, Jean Charbonneau, Johanne Charrette, Guy Choini\u00e8re, Dominique Cuffy, Linda Davery, Jos\u00e9e Dejean, Odette Demers, Laurence Depelteau-McEvoy, Francine Dimambro, Nicole Doucet, Louise Dufresne, Christiane Durand, Johanne Duval, Danielle Francoeur, Micheline Gagnon, Robert Gammon, Lawrence Gamache, Denise Gimeno, Henriette Grenon, Marie-H\u00e9l\u00e8ne H\u00e9bert, Lise Herault, Denise Huot, Chantal Jalbert, Nicole Jasmin, Nicole Julien, Joyce Kelly, Francine Labrie, Christiane Laforge, Andr\u00e9 Lalonde, Andr\u00e9e Lamarche, Marie Lamoureux, Linda Landry, Michelle Langevin, Anne-Marie Lapointe, Rollande Lapointe, Louise Latour, Lise Leduc, Christiane Lefebvre, Ginette Legros, Rachel Levesque, Jeanne Maranda, Gabrielle Martin-Garin, Carole Morissette, Madeleine Myre, Suzanne Nadeau, Kathleen O\u2019Keefe, Marybeth Painter, Madeleine Paquin, Pierrette Perodeau, Daniel Perras, Pierre-Andr\u00e9 Renaud, Sylvain Rouillard, Louise Salvas, Micheline Samson, Pierrette Scanlan, Louise Sperano, Francine St-Andr\u00e9, Lynn Starr, Johanne Th\u00e9roux, Julie Th\u00e9roux, Huguette Therrien, Jean Therrien, Claudette Tremblay, Marie Tremblay, Roger Tremblay, Rita Valli\u00e8re.<\/p>\n<h3>B\u00e9n\u00e9voles 2020 \u2013 \u00c9quipe r\u00e9duite<\/h3>\n<p>Jean Charbonneau, Daniel Chenevert, Michel Dagenais, Eric Lamothe, Brigitte Lapointe, Christine Latour, Jocelyne Laurencelle, Charline Lavoie, Claire Massicotte, Jimmy Pappas, Ga\u00e9tan P\u00e9pin, Chantal Tittley et Roger Tremblay.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;562&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;564&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;99&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;106&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;90&#8243; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;90&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;101&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1400","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;\u00e9quipe du FASS 2021 - Le Festival des Arts de Saint-Sauveur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;\u00e9quipe du FASS 2021 - Le Festival des Arts de Saint-Sauveur\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Festival des Arts de Saint-Sauveur\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FestivalDesArtsDeStSauveur\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-23T22:26:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@StSauveurFest\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/en\\\/lequipe-du-fass-2021\\\/\",\"url\":\"https:\\\/\\\/festivaldesarts.ca\\\/en\\\/lequipe-du-fass-2021\\\/\",\"name\":\"L'\u00e9quipe du FASS 2021 - Le Festival des Arts de Saint-Sauveur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/#website\"},\"datePublished\":\"2021-06-13T18:12:27+00:00\",\"dateModified\":\"2022-07-23T22:26:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/en\\\/lequipe-du-fass-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/festivaldesarts.ca\\\/en\\\/lequipe-du-fass-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/en\\\/lequipe-du-fass-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/festivaldesarts.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;\u00e9quipe du FASS 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/#website\",\"url\":\"https:\\\/\\\/festivaldesarts.ca\\\/\",\"name\":\"Le Festival des Arts de Saint-Sauveur\",\"description\":\"2025\",\"publisher\":{\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/festivaldesarts.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/#organization\",\"name\":\"Festival des Arts de Saint-Sauveur\",\"url\":\"https:\\\/\\\/festivaldesarts.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/festivaldesarts.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-FASS-NOIR-favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/festivaldesarts.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-FASS-NOIR-favicon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Festival des Arts de Saint-Sauveur\"},\"image\":{\"@id\":\"https:\\\/\\\/festivaldesarts.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FestivalDesArtsDeStSauveur\\\/\",\"https:\\\/\\\/x.com\\\/StSauveurFest\",\"https:\\\/\\\/www.instagram.com\\\/saint_sauveur_festival\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJpqlLLFeX8Ktmi3Kz6U-zA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'\u00e9quipe du FASS 2021 - Le Festival des Arts de Saint-Sauveur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/","og_locale":"en_US","og_type":"article","og_title":"L'\u00e9quipe du FASS 2021 - Le Festival des Arts de Saint-Sauveur","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221;...","og_url":"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/","og_site_name":"Le Festival des Arts de Saint-Sauveur","article_publisher":"https:\/\/www.facebook.com\/FestivalDesArtsDeStSauveur\/","article_modified_time":"2022-07-23T22:26:05+00:00","twitter_card":"summary_large_image","twitter_site":"@StSauveurFest","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/","url":"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/","name":"L'\u00e9quipe du FASS 2021 - Le Festival des Arts de Saint-Sauveur","isPartOf":{"@id":"https:\/\/festivaldesarts.ca\/#website"},"datePublished":"2021-06-13T18:12:27+00:00","dateModified":"2022-07-23T22:26:05+00:00","breadcrumb":{"@id":"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/festivaldesarts.ca\/en\/lequipe-du-fass-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/festivaldesarts.ca\/en\/"},{"@type":"ListItem","position":2,"name":"L&#8217;\u00e9quipe du FASS 2021"}]},{"@type":"WebSite","@id":"https:\/\/festivaldesarts.ca\/#website","url":"https:\/\/festivaldesarts.ca\/","name":"Le Festival des Arts de Saint-Sauveur","description":"2025","publisher":{"@id":"https:\/\/festivaldesarts.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/festivaldesarts.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/festivaldesarts.ca\/#organization","name":"Festival des Arts de Saint-Sauveur","url":"https:\/\/festivaldesarts.ca\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/festivaldesarts.ca\/#\/schema\/logo\/image\/","url":"https:\/\/festivaldesarts.ca\/wp-content\/uploads\/2021\/06\/cropped-FASS-NOIR-favicon.jpg","contentUrl":"https:\/\/festivaldesarts.ca\/wp-content\/uploads\/2021\/06\/cropped-FASS-NOIR-favicon.jpg","width":512,"height":512,"caption":"Festival des Arts de Saint-Sauveur"},"image":{"@id":"https:\/\/festivaldesarts.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FestivalDesArtsDeStSauveur\/","https:\/\/x.com\/StSauveurFest","https:\/\/www.instagram.com\/saint_sauveur_festival\/","https:\/\/www.youtube.com\/channel\/UCJpqlLLFeX8Ktmi3Kz6U-zA"]}]}},"_links":{"self":[{"href":"https:\/\/festivaldesarts.ca\/en\/wp-json\/wp\/v2\/pages\/1400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/festivaldesarts.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/festivaldesarts.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/festivaldesarts.ca\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/festivaldesarts.ca\/en\/wp-json\/wp\/v2\/comments?post=1400"}],"version-history":[{"count":0,"href":"https:\/\/festivaldesarts.ca\/en\/wp-json\/wp\/v2\/pages\/1400\/revisions"}],"wp:attachment":[{"href":"https:\/\/festivaldesarts.ca\/en\/wp-json\/wp\/v2\/media?parent=1400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}